{"id":27250,"date":"2026-02-05T13:20:55","date_gmt":"2026-02-05T11:20:55","guid":{"rendered":"https:\/\/2procente.info\/beneficiari\/parohia-romano-catolice-adormirea-maicii-domnului-3\/"},"modified":"2026-02-05T13:20:56","modified_gmt":"2026-02-05T11:20:56","slug":"parohia-romano-catolice-adormirea-maicii-domnului","status":"publish","type":"beneficiari","link":"https:\/\/2procente.info\/ru\/beneficiari\/parohia-romano-catolice-adormirea-maicii-domnului\/","title":{"rendered":"Parohia Romano-Catolice Adormirea Maicii Domnului"},"content":{"rendered":"<div class=\"elementor-element elementor-element-9f1c589 vertical-border-remove-yes elementor-widget elementor-widget-bdt-table\" data-id=\"9f1c589\" data-element_type=\"widget\" data-widget_type=\"bdt-table.default\">\n<div class=\"elementor-widget-container\">\n<div id=\"bdt-table-9f1c589\" class=\"bdt-table bdt-overflow-auto bdt-stripe\">\n<table>\n<tbody>\n<tr>\n<td style=\"width: 35%;\">Cod fiscal<\/td>\n<td style=\"color: #d63f49;\">1015620000818<\/td>\n<\/tr>\n<tr>\n<td>Forma juridic\u0103 de organizare<\/td>\n<td style=\"color: #d63f49;\">Cult religios<\/td>\n<\/tr>\n<tr>\n<td>Domeniul principal de activitate<\/td>\n<td style=\"color: #d63f49;\">Culte religioase<\/td>\n<\/tr>\n<tr>\n<td>Domeniul principal de activitate 1<\/td>\n<td style=\"color: #d63f49;\">Cultur\u0103\/Art\u0103<\/td>\n<\/tr>\n<tr>\n<td>Domeniul principal de activitate 2<\/td>\n<td style=\"color: #d63f49;\"><\/td>\n<\/tr>\n<tr>\n<td>Date de contact<\/td>\n<td style=\"color: #d63f49;\">https:\/\/www.facebook.com\/Parohia-Adormirea-Maicii-Domnului-and-centrul-pastoral-din-Orhei-693806414019801 <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cod fiscal 1015620000818 Forma juridic\u0103 de organizare Cult religios Domeniul principal de activitate Culte religioase Domeniul principal de activitate 1 Cultur\u0103\/Art\u0103 Domeniul principal de activitate 2 Date de contact https:\/\/www.facebook.com\/Parohia-Adormirea-Maicii-Domnului-and-centrul-pastoral-din-Orhei-693806414019801<\/p>\n","protected":false},"author":3,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"cybocfi_hide_featured_image":"","footnotes":""},"categorie-beneficiari":[84],"class_list":["post-27250","beneficiari","type-beneficiari","status-publish","format-standard","hentry","categorie-beneficiari-culte-religioase"],"acf":[],"_links":{"self":[{"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/beneficiari\/27250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/beneficiari"}],"about":[{"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/types\/beneficiari"}],"author":[{"embeddable":true,"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/beneficiari\/27250\/revisions"}],"predecessor-version":[{"id":28846,"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/beneficiari\/27250\/revisions\/28846"}],"wp:attachment":[{"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/media?parent=27250"}],"wp:term":[{"taxonomy":"categorie-beneficiari","embeddable":true,"href":"https:\/\/2procente.info\/ru\/wp-json\/wp\/v2\/categorie-beneficiari?post=27250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}